{"id":1321,"date":"2024-07-17T11:04:42","date_gmt":"2024-07-17T10:04:42","guid":{"rendered":"https:\/\/www.economistes-arabes.org\/fr\/?p=1321"},"modified":"2024-07-17T11:05:24","modified_gmt":"2024-07-17T10:05:24","slug":"le-liban-plonge-dans-une-crise-economique-sans-fin-entretien-avec-alternatives-economiques-samir-aita","status":"publish","type":"post","link":"https:\/\/www.economistes-arabes.org\/fr\/le-liban-plonge-dans-une-crise-economique-sans-fin-entretien-avec-alternatives-economiques-samir-aita\/","title":{"rendered":"Le Liban plong\u00e9 dans une crise \u00e9conomique sans fin. \u00ab\u00a0Alternatives Economiques\u00a0\u00bb: Entretien avec Samir AITA"},"content":{"rendered":"\n<p>Entretiens avec Samir AITA, Pr\u00e9sident du Cercle des Economistes Arabes<\/p>\n\n\n\n<p><strong><em>Selon vous, quelles sont les causes de la crise \u00e9conomique au Liban qui a d\u00e9but\u00e9 en 2019, et dans quelle mesure la pr\u00e9sence de r\u00e9fugi\u00e9s syriens (1,5 million de Syriens) affecte-t-elle cette crise ?<\/em><\/strong><\/p>\n\n\n\n<p>La crise au Liban ne date pas de 2019, mais de bien avant. Elle est due au mod\u00e8le \u00e9conomique et financier adopt\u00e9 \u00e0 la sortie de la guerre civile; en particulier la fixation du taux de change, la double mon\u00e9tarisation du pays, les hauts d&rsquo;int\u00e9r\u00eats servis, les rentes de l&rsquo;immobilier et des transferts des immigr\u00e9s.&nbsp; D\u00e9j\u00e0 en 2000, une premi\u00e8re crise s&rsquo;est d\u00e9clench\u00e9e, \u00e9vit\u00e9e in extremis par les conf\u00e9rences de Paris 1 et 2. La crise mondiale de 2008 avait constitu\u00e9e une manne pour le Liban, mais les choses se sont d\u00e9t\u00e9rior\u00e9s \u00e0 nouveau en 2011 avec le d\u00e9clenchement de la guerre en Syrie. La perte de confiance dans le pays et son syst\u00e8me bancaire libanais s&rsquo;est install\u00e9, et les banques \u00e9trang\u00e8res sont toutes sorties.<\/p>\n\n\n\n<p>L&rsquo;effondrement actuel a \u00e9t\u00e9 annonc\u00e9 d\u00e8s fin 2015 par les agences de notations. Le FMI a d\u00e9p\u00each\u00e9 une mission en 2016 confirmant les faits, mais son rapport a \u00e9t\u00e9 finalement modifi\u00e9 gr\u00e2ce aux interventions politiques internes et ext\u00e9rieures. La Banque Centrale a op\u00e9r\u00e9 une s\u00e9rie \u00ab\u00a0d&rsquo;ing\u00e9nierie financi\u00e8re\u00a0\u00bb retardant l&rsquo;effondrement jusqu&rsquo;en Octobre 2019. La Banque Mondiale qui avait fait auparavant l&rsquo;\u00e9loge du \u00ab\u00a0miracle\u00a0\u00bb libanais a fini apr\u00e8s la crise par qualifier les politiques mon\u00e9taires suivies comme un des plus grands \u00ab\u00a0sch\u00e9mas de Ponzi\u00a0\u00bb de l&rsquo;histoire mondiale. Plus de 70 milliards de dollars se sont \u00e9vapor\u00e9s. Ils n&rsquo;\u00e9taient en fait que des \u00e9critures de bilan.<\/p>\n\n\n\n<p>La pr\u00e9sence d&rsquo;un million et demi de r\u00e9fugi\u00e9s syriens a mis la pression sur les infrastructures publiques, d\u00e9j\u00e0 extr\u00eamement d\u00e9t\u00e9rior\u00e9es par l&rsquo;absence d&rsquo;investissement et les jeux des \u00ab\u00a0seigneurs\u00a0\u00bb politiques. Mais elle a aussi apport\u00e9 des milliards d&rsquo;aide et de transferts ext\u00e9rieurs \u00e0 ces r\u00e9fugi\u00e9s et aux libanais les plus d\u00e9munis. Elle a aussi permis \u00e0 l&rsquo;\u00e9conomie libanaise de profiter de main d&rsquo;\u0153uvre tr\u00e8s bon march\u00e9.<\/p>\n\n\n\n<p><strong><em>Comment \u00e9valuez-vous l\u2019impact de la corruption et de la mauvaise gestion sur cette crise ?<\/em><\/strong><\/p>\n\n\n\n<p>Les termes de \u00ab\u00a0corruption\u00a0\u00bb et de \u00ab\u00a0mauvaise gestion\u00a0\u00bb ne sont pas r\u00e9ellement les plus appropri\u00e9s. Il s&rsquo;agit de l&rsquo;\u00e9conomie politique syst\u00e9mique du syst\u00e8me libanais de l&rsquo;apr\u00e8s-guerre. Les \u00ab\u00a0seigneurs\u00a0\u00bb politiques dont les diff\u00e9rends minaient la vie politique et le fonctionnement des institutions se sont coalis\u00e9s au Parlement pour bloquer les r\u00e9formes urgentes n\u00e9cessaires d\u00e9but 2020, pourtant travaill\u00e9es entre le gouvernement et la Banque Lazard et approuv\u00e9es par le FMI. Les fuites de capitaux, d\u00e9marr\u00e9es en 2016, ont continu\u00e9 sans contr\u00f4le. Plus encore, alors que le taux de change r\u00e9el s&rsquo;est effondr\u00e9, on a permis aux emprunteurs en devises \u2013 et ils sont nombreux parmi ces seigneurs et leurs alli\u00e9s \u2013 de rembourser leurs emprunts aux taux officiel, c.a.d. au dixi\u00e8me de leur valeur. Ceci a annihil\u00e9 toute possibilit\u00e9 de rembourser les d\u00e9posants dans les banques, individuels ou institutionnels, dont les caisses de sant\u00e9 et de retraites. Aucune action n&rsquo;a \u00e9t\u00e9 entreprise vis-\u00e0-vis des banques, pourtant toutes techniquement insolvables. De plus, l&rsquo;Etat a continu\u00e9 \u00e0 percevoir les taxes et tarifs douaniers au taux officiel inchang\u00e9, ce qui a conduit \u00e0 la fuite de ces meilleurs cadres et \u00e0 r\u00e9duire son fonctionnement, y compris pour ce qui concerne les salaires de l&rsquo;arm\u00e9e et des forces de s\u00e9curit\u00e9 qui d\u00e9pendent aujourd&rsquo;hui des aides ext\u00e9rieures, am\u00e9ricaines, europ\u00e9ennes ou des pays du Golfe.<\/p>\n\n\n\n<p>Aucun responsable de l&rsquo;effondrement financier n&rsquo;a \u00e9t\u00e9 jug\u00e9; et l&rsquo;ancien gouverneur de la Banque Centrale vit en toute impunit\u00e9 dans le pays malgr\u00e9 les mandats d&rsquo;arr\u00eats libanais et \u00e9trangers contre lui. Aucun responsable de l&rsquo;explosion dramatique du port de Beyrouth n&rsquo;a \u00e9t\u00e9 jug\u00e9.<\/p>\n\n\n\n<p><strong><em>Comment la guerre \u00e0 Gaza et la d\u00e9t\u00e9rioration de la situation \u00e9conomique en Syrie en g\u00e9n\u00e9ral affectent-elles l\u2019\u00e9conomie libanaise ?<\/em><\/strong><\/p>\n\n\n\n<p>Le Liban est de facto entr\u00e9 en guerre au Sud le lendemain du d\u00e9clenchement de la guerre \u00e0 Gaza. S&rsquo;est install\u00e9e aussi la peur d&rsquo;une extension du conflit au-del\u00e0 des r\u00e8gles que les deux parties se sont impos\u00e9es jusqu&rsquo;\u00e0 pr\u00e9sent, avec notamment des bombardements et une invasion isra\u00e9lienne.&nbsp; Du coup, l&rsquo;activit\u00e9 \u00e9conomique s&rsquo;est ralentie et notamment le tourisme, bien qu&rsquo;il soit essentiellement d\u00fb aux immigr\u00e9s libanais.<\/p>\n\n\n\n<p>Le Liban profite de la d\u00e9t\u00e9rioration de la situation en Syrie. Avec les bombardements isra\u00e9liens syst\u00e9miques des a\u00e9roports de Damas et d&rsquo;Alep, c&rsquo;est l&rsquo;a\u00e9roport de Beyrouth qui sert de porte de voyage pour toute la Syrie. Les importations libanaises restent \u00e0 leur niveau d&rsquo;avant la crise, et avec les sanctions, le Liban sert de poumon \u00e9conomique \u00e0 la Syrie. Une partie de l&rsquo;aide internationale vers la Syrie transite aussi par le Liban.<\/p>\n\n\n\n<p>Mais avec l&rsquo;incertitude totale sur l&rsquo;avenir qu&rsquo;a ouvert Gaza, et les complicit\u00e9s internationales dans le g\u00e9nocide, l&rsquo;ambiance est morose, m\u00eame dans les milieux libanais ordinairement pro-occidentaux.<\/p>\n\n\n\n<p><strong><em>Comment l\u2019\u00c9gypte a-t-elle pu r\u00e9soudre rapidement son probl\u00e8me \u00e9conomique ?&nbsp;<\/em><\/strong><\/p>\n\n\n\n<p>Les causes profondes de la crise \u00e9gyptienne sont similaires \u00e0 ceux du Liban, avec en plus des d\u00e9penses d\u00e9mesur\u00e9es de l&rsquo;Etat. Mais cet Etat fonctionne en Egypte. D\u00e8s la fuite des 50 milliards de dollars de \u00ab\u00a0d\u00e9p\u00f4ts chauds\u00a0\u00bb en devises et les avoirs ext\u00e9rieurs totaux du pays devenus n\u00e9gatifs, comme on les appelle dans ce pays, l&rsquo;Etat a impos\u00e9 un contr\u00f4le dur des capitaux, limitant m\u00eame les importations de mati\u00e8res premi\u00e8res \u00e0 l&rsquo;industrie \u00e9gyptienne. Puis les pays du Golfe sont venus \u00e0 la rescousse, surtout les Emirats, avec des investissements directs d&rsquo;achats de terrains notamment sur la c\u00f4te m\u00e9diterran\u00e9enne, suivis par les pr\u00eats du FMI et de l&rsquo;Union Europ\u00e9enne. Les achats des bons du tr\u00e9sor \u00e9gyptien sont revenus. L&rsquo;Egypte est \u00ab\u00a0<em>too big to fail<\/em>\u00ab\u00a0, de peur d&rsquo;une crise migratoire vers l&rsquo;Europe ou d&rsquo;un changement de comportement dans les crises r\u00e9gionales.&nbsp;<\/p>\n\n\n\n<p>Mais ce \u00ab\u00a0sauvetage\u00a0\u00bb&nbsp; rappelle celui des conf\u00e9rences de Paris I et II pour le Liban. Il y a des coupures r\u00e9guli\u00e8res de l&rsquo;\u00e9lectricit\u00e9 dans le pays, bien qu&rsquo;il soit exportateur de gaz! Sa balance courante reste n\u00e9gative, malgr\u00e9 les transferts importants des immigr\u00e9s et les revenus &#8211; il est vrai actuellement r\u00e9duits &#8211; du Canal de Suez. L\u00e0 aussi il y a une crise du mod\u00e8le \u00e9conomique, et du fonctionnement des \u00e9lites politiques\u2026 et militaires.<\/p>\n\n\n\n<p><strong><em>Comment les pays de la r\u00e9gion et les \u00c9tats peuvent-ils aider le Liban \u00e0 surmonter sa crise \u00e9conomique ?<\/em><\/strong><\/p>\n\n\n\n<p>Seul l&rsquo;Iraq a aid\u00e9 le Liban s\u00e9rieusement jusqu&rsquo;\u00e0 pr\u00e9sent avec des fournitures de p\u00e9trole brut, qui doit \u00eatre raffin\u00e9 avant de servir pour les centrales \u00e9lectriques. Les pays du Golfe ont arr\u00eat\u00e9 les importations des fruits et l\u00e9gumes libanais, pourtant essentiels pour le Liban, suite \u00e0 la d\u00e9couverte aux douanes d&rsquo;une exp\u00e9dition de Captagon cach\u00e9e. On n&rsquo;a jamais su \u00e0 quelle soci\u00e9t\u00e9 elle \u00e9tait destin\u00e9e.<\/p>\n\n\n\n<p>L&rsquo;Egypte, l&rsquo;Arabie Saudite et le Qatar sont dans une commission des 5, avec la France et les Etats Unis, cens\u00e9e aider le pays \u00e0 \u00e9lire un Pr\u00e9sident apr\u00e8s un vide institutionnel de 18 mois. Mais tous ces acteurs ont un probl\u00e8me avec le Hezbollah qui est devenu un interlocuteur incontournable de la vie politique.<\/p>\n\n\n\n<p>A ce blocage, s&rsquo;ajoute celui de la classe politique libanaise qui retarde tout type de r\u00e9forme \u00e9conomique et financi\u00e8re, jusqu&rsquo;au moment o\u00f9 les d\u00e9posants, libanais et autres, perdent espoir de r\u00e9cup\u00e9rer leurs dus. On ne peut s&rsquo;attendre dans ce contexte \u00e0 une manne financi\u00e8re sauvant le pays.<\/p>\n\n\n\n<p><strong><em>Quels sont les obstacles \u00e0 un soutien international efficace au Liban ?<\/em><\/strong><\/p>\n\n\n\n<p>On n&rsquo;est plus dans un contexte o\u00f9 la France pouvait les conf\u00e9rences de Paris I et II, malgr\u00e9 \u00ab\u00a0l&rsquo;occupation syrienne\u00a0\u00bb, ni m\u00eame pour lancer les investissements promis dans la conf\u00e9rence C\u00e8dre de 2018. Le Liban est class\u00e9 internationalement aujourd&rsquo;hui comme \u00ab\u00a0Etat Fragile\u00a0\u00bb, et m\u00eame le FMI avoue qu&rsquo;il n&rsquo;a r\u00e9ellement d&rsquo;outils pour le sortir de cette fragilit\u00e9. Nous sommes \u00e9galement apr\u00e8s le tournant historique de la guerre de Gaza, o\u00f9 l&rsquo;on parle d&rsquo;un \u00ab\u00a0ordre nouveau\u00a0\u00bb \u00e0 \u00e9tablir dans la r\u00e9gion; et il semble qu&rsquo;il n\u00e9cessite pour le Liban l&rsquo;\u00e9limination du Hezbollah ou au moins le partage du pays avec une \u00ab\u00a0d\u00e9centralisation \u00e9tendue\u00a0\u00bb.<\/p>\n\n\n\n<p>Seuls les libanais eux-m\u00eames peuvent sortir leur pays de son impasse, en jouant les compromis internes n\u00e9cessaires pour r\u00e9tablir le fonctionnement de leurs institutions, op\u00e9rer les r\u00e9formes et \u0153uvrer pour un r\u00f4le \u00e9conomique nouveau dans la r\u00e9gion, profitant de leur main d&rsquo;\u0153uvre sensiblement qualifi\u00e9e, arr\u00eatant son h\u00e9morragie actuelle.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><\/figure><div class=\"wp-block-media-text__content\">\n<p><a href=\"https:\/\/www.alternatives-economiques.fr\/liban-plonge-une-crise-economique-fin\/00111728\">https:\/\/www.alternatives-economiques.fr\/liban-plonge-une-crise-economique-fin\/00111728<\/a><\/p>\n<\/div><\/div>\n<!-- Facebook Page Plugin by Medust: http:\/\/medust.com -->\r\n\t\t<div class=\"fb-recommendations-bar\" data-href=\"https:\/\/www.economistes-arabes.org\/fr\/le-liban-plonge-dans-une-crise-economique-sans-fin-entretien-avec-alternatives-economiques-samir-aita\/\" data-read-time=\"5\" data-side=\"\" data-action=\"like\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Entretiens avec Samir AITA, Pr\u00e9sident du Cercle des Economistes Arabes Selon vous, quelles sont les causes de la crise \u00e9conomique au Liban qui a d\u00e9but\u00e9 en 2019, et dans quelle mesure la pr\u00e9sence de r\u00e9fugi\u00e9s syriens (1,5 million de Syriens)<a class=\"more-link\" href=\"https:\/\/www.economistes-arabes.org\/fr\/le-liban-plonge-dans-une-crise-economique-sans-fin-entretien-avec-alternatives-economiques-samir-aita\/\">Read more&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"chat","meta":{"footnotes":""},"categories":[3,20,18,13],"tags":[],"class_list":["post-1321","post","type-post","status-publish","format-chat","has-post-thumbnail","hentry","category-activites-recentes","category-articles-interessants","category-finances-publiques","category-publications","post_format-post-format-chat"],"_links":{"self":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/1321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/comments?post=1321"}],"version-history":[{"count":2,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/1321\/revisions"}],"predecessor-version":[{"id":1324,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/1321\/revisions\/1324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media\/1323"}],"wp:attachment":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media?parent=1321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/categories?post=1321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/tags?post=1321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}