{"id":158,"date":"2013-02-15T18:53:40","date_gmt":"2013-02-15T17:53:40","guid":{"rendered":"http:\/\/www.economistes-arabes.org\/fr\/?p=158"},"modified":"2014-05-31T23:46:35","modified_gmt":"2014-05-31T22:46:35","slug":"158","status":"publish","type":"post","link":"https:\/\/www.economistes-arabes.org\/fr\/158\/","title":{"rendered":"Georges Corm: Le blocage des transitions d\u00e9mocratiques arabes"},"content":{"rendered":"<p><strong>Le Cercle des Economistes Arabes<\/strong><\/p>\n<p class=\"paragraph_style_17\" style=\"font-weight: bold; color: #000000;\">en partenariat avec Le Monde Diplomatique \u00e9ditions arabes et le Master Management des entreprises des pays \u00e9mergeants et en d\u00e9veloppement<\/p>\n<p class=\"paragraph_style_18\" style=\"font-weight: bold; color: #002060;\">Conf\u00e9rence: Le blocage des transitions d\u00e9mocratiques arabes: L\u2019absence de Dynamiques de Changement Socio-\u00e9conomique<\/p>\n<p class=\"paragraph_style_28\" style=\"color: #000000;\"><a style=\"color: #7d8389;\" title=\"Nos_conferences_files\/Corm 2013.pdf\" href=\"http:\/\/www.economistes-arabes.org\/Cercle_des_economistes_arabes\/Nos_conferences_files\/Corm%202013.pdf\">Conf\u00e9rence anim\u00e9e par\u00a0:<br \/>\n<\/a><\/p>\n<p class=\"paragraph_style_29\" style=\"font-weight: bold; color: #000000;\"><a style=\"color: #7d8389;\" title=\"Nos_conferences_files\/Corm 2013_1.pdf\" href=\"http:\/\/www.economistes-arabes.org\/Cercle_des_economistes_arabes\/Nos_conferences_files\/Corm%202013_1.pdf\">Mr. Georges Corm<br \/>\n<\/a><\/p>\n<p class=\"paragraph_style_30\" style=\"color: #000000;\"><a style=\"color: #7d8389;\" title=\"Nos_conferences_files\/Corm 2013_2.pdf\" href=\"http:\/\/www.economistes-arabes.org\/Cercle_des_economistes_arabes\/Nos_conferences_files\/Corm%202013_2.pdf\">Ecrivain et ancien Ministre libanais des Finances<\/a><\/p>\n<p class=\"paragraph_style_32\" style=\"color: #002f73;\"><a style=\"color: #7d8389;\" title=\"Nos_conferences_files\/Corm 2013_4.pdf\" href=\"http:\/\/www.economistes-arabes.org\/Cercle_des_economistes_arabes\/Nos_conferences_files\/Corm%202013_4.pdf\">Les r\u00e9voltes arabes suscitent de plus en plus de d\u00e9ceptions, d\u2019inqui\u00e9tude et de violences. Une des causes internes majeures des situations actuelles est \u00e0 rechercher dans la survalorisation du \u00ab\u00a0politique\u00a0\u00bb au d\u00e9triment de l\u2019\u00e9conomique et du social, moteur majeur des mobilisations populaires. Aucune force politique n\u2019a malheureusement d\u00e9velopp\u00e9 un programme de sortie de l\u2019\u00e9conomie de rente, responsable des injustices socio-\u00e9conomiques et des sous-performances des \u00e9conomies arabes. Les \u00e9conomistes arabes devraient s\u00e9rieusement se mobiliser autour de ce th\u00e8me.<\/a><\/p>\n<p class=\"paragraph_style_34\" style=\"font-weight: bold; color: #ff2600;\"><a style=\"color: #7d8389;\" title=\"Nos_conferences_files\/Corm 2013_6.pdf\" href=\"http:\/\/www.economistes-arabes.org\/Cercle_des_economistes_arabes\/Nos_conferences_files\/Corm%202013_6.pdf\">Le\u00a0Vendredi 15 F\u00e9vrier 2013 \u00e0 18h30<\/a><\/p>\n<p class=\"paragraph_style_36\" style=\"font-weight: bold; color: #000000;\"><a style=\"color: #7d8389;\" title=\"Nos_conferences_files\/Corm 2013_8.pdf\" href=\"http:\/\/www.economistes-arabes.org\/Cercle_des_economistes_arabes\/Nos_conferences_files\/Corm%202013_8.pdf\">Salle 709 de l\u2019Universit\u00e9 Paris Dauphine, 1<span class=\"style_15\">er<\/span>\u00a0\u00e9tage, Aile A<br \/>\n<\/a><\/p>\n<p class=\"paragraph_style_36\" style=\"font-weight: bold; color: #000000;\"><a style=\"color: #7d8389;\" title=\"Nos_conferences_files\/Corm 2013_9.pdf\" href=\"http:\/\/www.economistes-arabes.org\/Cercle_des_economistes_arabes\/Nos_conferences_files\/Corm%202013_9.pdf\">Place du Mar\u00e9chal de Lattre de Tassigny, 75116 Paris<\/a><\/p>\n<!-- Facebook Page Plugin by Medust: http:\/\/medust.com -->\r\n\t\t<div class=\"fb-recommendations-bar\" data-href=\"https:\/\/www.economistes-arabes.org\/fr\/158\/\" data-read-time=\"5\" data-side=\"\" data-action=\"like\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Le Cercle des Economistes Arabes en partenariat avec Le Monde Diplomatique \u00e9ditions arabes et le Master Management des entreprises des pays \u00e9mergeants et en d\u00e9veloppement Conf\u00e9rence: Le blocage des transitions d\u00e9mocratiques arabes: L\u2019absence de Dynamiques de Changement Socio-\u00e9conomique Conf\u00e9rence anim\u00e9e<a class=\"more-link\" href=\"https:\/\/www.economistes-arabes.org\/fr\/158\/\">Read more&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"chat","meta":{"footnotes":""},"categories":[3,7],"tags":[],"class_list":["post-158","post","type-post","status-publish","format-chat","has-post-thumbnail","hentry","category-activites-recentes","category-les-conferences-du-cercle","post_format-post-format-chat"],"_links":{"self":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/comments?post=158"}],"version-history":[{"count":4,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/158\/revisions"}],"predecessor-version":[{"id":162,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/158\/revisions\/162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media\/227"}],"wp:attachment":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media?parent=158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/categories?post=158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/tags?post=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}