{"id":413,"date":"2011-06-15T11:35:21","date_gmt":"2011-06-15T10:35:21","guid":{"rendered":"http:\/\/www.economistes-arabes.org\/fr\/?p=413"},"modified":"2014-06-04T11:36:21","modified_gmt":"2014-06-04T10:36:21","slug":"el-mouhoub-mouhoud-pourquoi-les-allemands-tout-en-delocalisant-creent-aussi-des-emplois","status":"publish","type":"post","link":"https:\/\/www.economistes-arabes.org\/fr\/el-mouhoub-mouhoud-pourquoi-les-allemands-tout-en-delocalisant-creent-aussi-des-emplois\/","title":{"rendered":"El Mouhoub Mouhoud : \u201cPourquoi les allemands, tout en d\u00e9localisant, cr\u00e9ent aussi des emplois?\u201d."},"content":{"rendered":"<p><span class=\"style_1\" style=\"color: #222504;\">Participation de El Mouhoub Mouhoud \u00e0 l\u2019emission \u201cDu Grain \u00e0 Moudre\u201d sur France Culture le 15 juin 2011 sur le sujet suivant: \u201cPourquoi les allemands, tout en d\u00e9localisant, cr\u00e9ent aussi des emplois?\u201d.\u00a0<\/span><a class=\"style_3\" style=\"font-style: italic; color: #7d8389;\" title=\"http:\/\/www.franceculture.com\/emission-du-grain-a-moudre-pourquoi-les-allemands-tout-en-delocalisant-creent-aussi-des-emplois-2011\" href=\"http:\/\/www.franceculture.com\/emission-du-grain-a-moudre-pourquoi-les-allemands-tout-en-delocalisant-creent-aussi-des-emplois-2011\">Cliquer ici pour acc\u00e9der \u00e0 l\u2019\u00e9mission<\/a><span class=\"style_1\" style=\"color: #222504;\">.<\/span><\/p>\n<!-- Facebook Page Plugin by Medust: http:\/\/medust.com -->\r\n\t\t<div class=\"fb-recommendations-bar\" data-href=\"https:\/\/www.economistes-arabes.org\/fr\/el-mouhoub-mouhoud-pourquoi-les-allemands-tout-en-delocalisant-creent-aussi-des-emplois\/\" data-read-time=\"5\" data-side=\"\" data-action=\"like\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Participation de El Mouhoub Mouhoud \u00e0 l\u2019emission \u201cDu Grain \u00e0 Moudre\u201d sur France Culture le 15 juin 2011 sur le sujet suivant: \u201cPourquoi les allemands, tout en d\u00e9localisant, cr\u00e9ent aussi des emplois?\u201d.\u00a0Cliquer ici pour acc\u00e9der \u00e0 l\u2019\u00e9mission.<\/p>\n","protected":false},"author":1,"featured_media":335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"chat","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-413","post","type-post","status-publish","format-chat","has-post-thumbnail","hentry","category-activites-recentes","category-non-classe","post_format-post-format-chat"],"_links":{"self":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/comments?post=413"}],"version-history":[{"count":1,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/413\/revisions"}],"predecessor-version":[{"id":414,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/413\/revisions\/414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media\/335"}],"wp:attachment":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media?parent=413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/categories?post=413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/tags?post=413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}