{"id":522,"date":"2014-07-07T07:01:44","date_gmt":"2014-07-07T06:01:44","guid":{"rendered":"http:\/\/www.economistes-arabes.org\/fr\/?p=522"},"modified":"2014-07-07T07:02:17","modified_gmt":"2014-07-07T06:02:17","slug":"le-cercle-des-economistes-arabes-participent-a-lassemblee-generale-de-locemo","status":"publish","type":"post","link":"https:\/\/www.economistes-arabes.org\/fr\/le-cercle-des-economistes-arabes-participent-a-lassemblee-generale-de-locemo\/","title":{"rendered":"Le Cercle des Economistes Arabes participe \u00e0 l&rsquo;Assembl\u00e9e G\u00e9n\u00e9rale de l&rsquo;OCEMO"},"content":{"rendered":"<p>L&rsquo;assembl\u00e9e g\u00e9n\u00e9rale de l&rsquo;OCEMO s&rsquo;est tenue \u00e0 Marseille le 3 juillet 2013. Samir AITA y a particip\u00e9 au nom du Cercle des Economistes Arabes.<\/p>\n<p>L&rsquo;OCEMO a \u00e9lu deux co-pr\u00e9sidents:\u00a0<span style=\"color: #333333;\">\u00a0<strong>Madame\u00a0<\/strong><\/span><strong style=\"color: #333333;\">Assia Bensalah Alaoui et Monsieur Mou\u00efn Hamze.\u00a0<a href=\"http:\/\/www.ocemo.org\/L-Office-de-Cooperation-Economique-pour-la-Mediterranee-et-l-Orient-OCEMO-renforce-sa-gouvernance_a402.html\">L\u2019Office de Coop\u00e9ration Economique pour la M\u00e9diterran\u00e9e et l\u2019Orient (OCEMO) renforce sa gouvernance<\/a>.\u00a0<\/strong><\/p>\n<p>Durant l&rsquo;AG, le Cercle a \u00e9voqu\u00e9 plusieurs sujets de coop\u00e9ration des r\u00e9seaux qui peuvent \u00eatre men\u00e9 dans les prochains mois:<\/p>\n<ul>\n<li><strong>Les id\u00e9es pour les r\u00e9formes en Tunisie<\/strong>, en appui au gouvernement actuel de transition. Une r\u00e9union des int\u00e9ress\u00e9s devrait \u00eatre organis\u00e9e dans les prochains jours.<\/li>\n<li><strong>Les id\u00e9es pour la reconstruction de la Syrie<\/strong>, apr\u00e8s la fin de la guerre. Egalement des consultations doivent se faire pour les expressions d&rsquo;int\u00e9r\u00eat.<\/li>\n<li><strong>L&rsquo;accueil des \u00e9tudiants syriens en France et dans les autres pays m\u00e9diterran\u00e9ens<\/strong>. Le tiers des \u00e9tudiants ne peuvent acc\u00e9der \u00e0 leurs universit\u00e9s du fait de la situation actuelle. Et la ville de Marseille peut jouer un r\u00f4le de leadership en mati\u00e8re d&rsquo;accueil, permettant \u00e0 ses jeunes de poursuivre leurs \u00e9tudes afin de revenir un jour reconstruire leur pays.<\/li>\n<\/ul>\n<!-- Facebook Page Plugin by Medust: http:\/\/medust.com -->\r\n\t\t<div class=\"fb-recommendations-bar\" data-href=\"https:\/\/www.economistes-arabes.org\/fr\/le-cercle-des-economistes-arabes-participent-a-lassemblee-generale-de-locemo\/\" data-read-time=\"5\" data-side=\"\" data-action=\"like\"><\/div>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;assembl\u00e9e g\u00e9n\u00e9rale de l&rsquo;OCEMO s&rsquo;est tenue \u00e0 Marseille le 3 juillet 2013. Samir AITA y a particip\u00e9 au nom du Cercle des Economistes Arabes. L&rsquo;OCEMO a \u00e9lu deux co-pr\u00e9sidents:\u00a0\u00a0Madame\u00a0Assia Bensalah Alaoui et Monsieur Mou\u00efn Hamze.\u00a0L\u2019Office de Coop\u00e9ration Economique pour la<a class=\"more-link\" href=\"https:\/\/www.economistes-arabes.org\/fr\/le-cercle-des-economistes-arabes-participent-a-lassemblee-generale-de-locemo\/\">Read more&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"chat","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-522","post","type-post","status-publish","format-chat","has-post-thumbnail","hentry","category-activites-recentes","category-non-classe","post_format-post-format-chat"],"_links":{"self":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/comments?post=522"}],"version-history":[{"count":2,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/522\/revisions"}],"predecessor-version":[{"id":525,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/posts\/522\/revisions\/525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/media?parent=522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/categories?post=522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.economistes-arabes.org\/fr\/wp-json\/wp\/v2\/tags?post=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}